{"id":14110,"date":"2023-04-19T09:38:08","date_gmt":"2023-04-19T07:38:08","guid":{"rendered":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/?p=14110"},"modified":"2023-05-24T09:43:48","modified_gmt":"2023-05-24T07:43:48","slug":"profesionales-libres-radicales-libres","status":"publish","type":"post","link":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/profesionales-libres-radicales-libres\/","title":{"rendered":"Profesionales Libres. Radicales Libres"},"content":{"rendered":"<div id=\"telet-1114165980\" class=\"telet-antes-del-contenido telet-entity-placement\"><a href=\"https:\/\/quaderno.io\/?via=jose-manuel94\" aria-label=\"Quaderno General (Spanish) &#8211; 728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1.png\" alt=\"\"  srcset=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1.png 728w, https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1-300x37.png 300w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Hace unos meses hac\u00eda una comparaci\u00f3n entre los <a href=\"https:\/\/www.andresperezortega.com\/2022\/11\/profesional-libre-el-cuarto-estado-profesional.html\" target=\"_blank\" rel=\"noreferrer noopener\">estados de la materia y los estados profesionales<\/a>. Dec\u00eda que los Profesionales Libres son algo as\u00ed como el cuarto estado en el que podemos situarnos laboralmente.<\/p>\n<p>B\u00e1sicamente trataba de explicar que un Profesional Libre se sit\u00faa en una posici\u00f3n que le permite \u00abreaccionar\u00bb con cualquiera que pueda necesitar sus servicios independientemente de su calificaci\u00f3n administrativa.<\/p>\n<p>Hay otra met\u00e1fora \u00abqu\u00edmica\u00bb que se puede asociar a los profesionales que no se pueden encasillar en los estereotipos cl\u00e1sicos (desempleado, empleado, emprendedor\/empresario). Me refiero a los Radicales Libres.<\/p>\n<p>Si no te acuerdas lo que te contaron en el colegio sobre los Radicales Libres te dir\u00e9 que seg\u00fan la Wikipedia:<\/p>\n<blockquote class=\"wp-block-quote\"><p>En\u00a0qu\u00edmica, un\u00a0<strong>radical<\/strong>\u00a0(antes\u00a0<strong>radical libre<\/strong>\u200b) es una\u00a0especie qu\u00edmica\u00a0(org\u00e1nica\u00a0o\u00a0inorg\u00e1nica), caracterizada por poseer uno o m\u00e1s\u00a0electrones desapareados. Se forma en el intermedio de reacciones qu\u00edmicas, a partir de la\u00a0ruptura homol\u00edtica\u00a0de una mol\u00e9cula y, en general, es extremadamente\u00a0inestable\u00a0y, por tanto, con gran poder\u00a0reactivo\u00a0y de vida media muy corta (milisegundos).\u200b<\/p><\/blockquote>\n<p>Creo que estas l\u00edneas describen perfectamente la mentalidad de Profesional Libre<\/p>\n<h4 class=\"wp-block-heading\">Posee uno o m\u00e1s electrones desapareados<\/h4>\n<p>Explicado de forma sencilla, que un \u00e1tomo tenga electrones desapareados le proporciona unas propiedades especiales. Podr\u00edamos decir que un Profesional Libre tiene una o m\u00e1s cualidades desapareadas, es decir, que tiene unas caracter\u00edsticas que le empujan a relacionarse o interactuar de formas distintas a las habituales.<\/p>\n<p>Un Profesional Libre no se limita a hacer lo que le dicen o a cumplir \u00f3rdenes dentro de una estructura s\u00f3lida e inmutable sino que constantemente est\u00e1 buscando forma de \u00abaparear\u00bb esa pasi\u00f3n, intereses, habilidades o experiencia en cualquier sitio en el que puedan ser \u00fatiles.<\/p>\n<p>Eso le impide quedarse quieto en un \u00abestado\u00bb profesional definido.<\/p>\n<p>Un Profesional Libre nunca se considerar\u00e1 \u00abparado\u00bb aunque moment\u00e1neamente est\u00e9 sin \u00abaparearse\u00bb, sin clientes o empleador. Simplemente estar\u00e1 buscando o creando nuevos proyectos o incluso manteniendo alguno de los que ha ido poniendo en marcha.<\/p>\n<p>Un Profesional Libre nunca considerar\u00e1 que un empleo es el objetivo sino que esa ser\u00e1 una de sus opciones, de sus fuentes de ingresos. Aunque trabajar por cuenta ajena, de 9 a 5, pueda exigirle la mayor parte de su tiempo (hasta que pueda escapar), puede dedicar el resto, de 5 a 9, a poner en marcha peque\u00f1as o grandes ideas de negocio propias.<\/p>\n<p>Un Profesional Libre nunca considerar\u00e1 que ser empresario es la meta final sino que montar una empresa s\u00f3lo es uno de sus proyectos. Quiz\u00e1s sea el m\u00e1s grande, pero ni el \u00faltimo ni el definitivo.<\/p>\n<p><a href=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14111\" src=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales-890x501.jpg\" alt=\"\" width=\"890\" height=\"501\" srcset=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales-890x501.jpg 890w, https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales-300x169.jpg 300w, https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales-768x432.jpg 768w, https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/4EstadosProfesionales.jpg 1280w\" sizes=\"auto, (max-width: 890px) 100vw, 890px\" \/><\/a><\/p>\n<h4 class=\"wp-block-heading\">Es extremadamente\u00a0inestable y con gran poder\u00a0reactivo<\/h4>\n<p>Un Profesional (o un Radical) Libre es extremadamente inestable, pero eso no es necesariamente negativo, simplemente indica su inquietud, su mentalidad siempre alerta para reaccionar.<\/p>\n<p>Esa inestabilidad quiz\u00e1s le complica la vida cuando se trata de mantener unos enlaces duraderos cuando trabaja para otros, pero le facilita las cosas para innovar, crear y cambiar.<\/p>\n<p>El cambio forma parte del Profesional Libre y no s\u00f3lo no le disgusta sino que lo considera una fuente de oportunidades. Un problema no es algo negativo sino una posibilidad de mejora.<\/p>\n<p>El Profesional Libre est\u00e1 siempre pendiente de lo nuevo, de las tendencias, de lo que hacen otros Radicales Libres y busca formas de crear \u00abenlaces\u00bb originales, nuevos, incluso extra\u00f1os.<\/p>\n<p>Curiosamente aunque hablemos de la capacidad de los Profesionales Libres para la reacci\u00f3n, en este caso podr\u00edamos hablar m\u00e1s bien de la acci\u00f3n.<\/p>\n<h4 class=\"wp-block-heading\">Con una vida media muy corta<\/h4>\n<p>Hablar de una vida media muy corta se refiere a los proyectos que pone en marcha, no al Profesional Libre (espero).<\/p>\n<p>Una de las caracter\u00edsticas que diferencia a un Profesional Libre del empresario o emprendedor es el tama\u00f1o de los proyectos que pone en marcha.<\/p>\n<p>El Profesional Libre puede considerar un empleo como uno de sus proyectos, o puede poner en marcha grandes negocios propios, pero lo que caracteriza a esta mentalidad es la de crear Proyectos Paralelos que se ponen en marcha con rapidez y pocos recursos.<\/p>\n<p>En este caso con lo de la vida media corta me refiero a la velocidad de implantaci\u00f3n, no a su duraci\u00f3n.<\/p>\n<p>Una web comercial, un manual, un podcast de pago, un taller, una asesor\u00eda a distancia, un producto virtual de cualquier tipo,\u2026 Las posibilidades son enormes\u2026 y r\u00e1pidas de implementar.<\/p>\n<p>Si esos proyectos no salen adelante o son un completo fracaso, las p\u00e9rdidas ser\u00e1n m\u00e1s morales que econ\u00f3micas, pero habr\u00e1n sentado las bases para los siguientes.<\/p>\n<p>Creo que el futuro es de los Profesionales Libres, de los que quieran ocupar ese cuarto estado de la materia profesional, de los que utilicen su capacidad para crear enlaces en lugar de mantenerse estables e inertes.<\/p>\n<p><a href=\"https:\/\/www.andresperezortega.com\"><em>Andres Perez Ortega<\/em><\/a><\/p>\n<div id=\"telet-547841976\" class=\"telet-despues-del-contenido telet-entity-placement\"><a target=\"_blank\" href=\"\/\/aff.lucushost.com\/resources\/click\/?n=gDxoXMAJ&aff=756\"><img decoding=\"async\" border=\"0\" alt=\"LucusHost, el mejor hosting\" src=\"\/\/aff.lucushost.com\/resources\/banners\/?zoneid=5123&n=gDxoXMAJ&aff=756\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Hace unos meses hac\u00eda una comparaci\u00f3n entre los estados de la materia y los estados profesionales. Dec\u00eda que los Profesionales Libres son algo as\u00ed como el cuarto estado en el&hellip; <\/p>\n","protected":false},"author":1,"featured_media":14112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[6],"tags":[20,19],"class_list":["post-14110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marca-personal","tag-fuprisa","tag-jose-manuel-fuentes-prieto"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"jetpack_featured_media_url":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2023\/05\/hombre-calculando-pago-impuestos.jpg","_links":{"self":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/14110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/comments?post=14110"}],"version-history":[{"count":1,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/14110\/revisions"}],"predecessor-version":[{"id":14113,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/14110\/revisions\/14113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/media\/14112"}],"wp:attachment":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/media?parent=14110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/categories?post=14110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/tags?post=14110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}