{"id":9450,"date":"2022-06-07T10:52:27","date_gmt":"2022-06-07T08:52:27","guid":{"rendered":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/?p=9450"},"modified":"2022-06-07T10:52:27","modified_gmt":"2022-06-07T08:52:27","slug":"utiliza-la-regla-del-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra","status":"publish","type":"post","link":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/utiliza-la-regla-del-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra\/","title":{"rendered":"Utiliza la regla del 70% para que el perfeccionismo no juegue en tu contra"},"content":{"rendered":"<div id=\"telet-2936021314\" class=\"telet-antes-del-contenido telet-entity-placement\"><a href=\"https:\/\/quaderno.io\/?via=jose-manuel94\" aria-label=\"Quaderno General (Spanish) &#8211; 728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1.png\" alt=\"\"  srcset=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1.png 728w, https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/11\/Quaderno-General-Spanish-728x90-1-300x37.png 300w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Tengamos cuidado al plantearnos objetivos demasiado exigentes y esperar resultados \u00f3ptimos: puede ser contraproducente. Esta regla te ayudar\u00e1 a usar el perfeccionismo a tu favor. \u00a1Descubre c\u00f3mo!<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\"><strong>\u00bfSab\u00edas que el perfeccionismo puede impedirnos transformarnos en grandes artistas?<\/strong>\u00a0De hecho, puede ser un palo en la rueda para cualquiera de nuestros sue\u00f1os. \u00bfNo me crees? Piensa cu\u00e1ntas veces has dejado de hacer algo simplemente por miedo a fallar o no obtener los resultados esperados.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\"><strong>La b\u00fasqueda de la excelencia puede jugarnos una mala pasada<\/strong>\u00a0si la ansiedad por cometer errores nos lleva a abandonar o dejar proyectos por la mitad. Perder el miedo a equivocarse es uno de los secretos para procrastinar menos y no desperdiciar las oportunidades que nos brindamos al pasar a la acci\u00f3n.<\/p>\n<h2 id=\"un-arma-de-doble-filo\" class=\"jsx-3692753319 jsx-2566528898 c--main-600  mt--x-big pt--normal\">Un arma de doble filo<\/h2>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">El perfeccionismo es un rasgo de personalidad que se caracteriza por la b\u00fasqueda sistem\u00e1tica -pero muchas veces insaciable- de resultados \u00f3ptimos. Definirlo en t\u00e9rminos de \u201cbueno\u201d o \u201cmalo\u201d, no tiene mucho sentido. Lo cierto es que seg\u00fan c\u00f3mo lo utilicemos, puede jugarnos en contra o a nuestro favor.<\/p>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2020\/07\/articulos.png\" \/><\/p>\n<p>[wp-rss-aggregator template=\u00bbDefault\u00bb]<\/p>\n<hr \/>\n<h3 id=\"perfeccionismo-desadaptativo\" class=\"jsx-3692753319 jsx-2566528898 c--main-600  mt--x-big pt--normal\">Perfeccionismo desadaptativo<\/h3>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Cuando el perfeccionismo impone una\u00a0<a class=\"jsx-151512268 jsx-1474443579 default-a-link is--underline c--secondary-600 is--underline\" href=\"https:\/\/lamenteesmaravillosa.com\/la-autoexigencia-y-la-necesidad-de-control\/\" target=\"_self\" rel=\"noopener\" data-with-google-events=\"true\" data-google-events=\"{&quot;data&quot;:{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;Content&quot;,&quot;label&quot;:&quot;Related \/utiliza-regla-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra\/?adsafe_ip=&quot;,&quot;value&quot;:&quot;https:\/\/lamenteesmaravillosa.com\/la-autoexigencia-y-la-necesidad-de-control\/&quot;}}\">autoexigencia<\/a>\u00a0desmedida, una dura\u00a0<a class=\"jsx-151512268 jsx-1474443579 default-a-link is--underline c--secondary-600 is--underline\" href=\"https:\/\/lamenteesmaravillosa.com\/de-la-autocritica-destructiva-a-la-autocritica-compasiva\/\" target=\"_self\" rel=\"noopener\" data-with-google-events=\"true\" data-google-events=\"{&quot;data&quot;:{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;Content&quot;,&quot;label&quot;:&quot;Related \/utiliza-regla-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra\/?adsafe_ip=&quot;,&quot;value&quot;:&quot;https:\/\/lamenteesmaravillosa.com\/de-la-autocritica-destructiva-a-la-autocritica-compasiva\/&quot;}}\">autocr\u00edtica<\/a>, y una rigidez mental que se hace presente en la imposibilidad de flexibilizar las metas propuestas o adaptarse frente a los obst\u00e1culos, resulta un rasgo altamente desadaptativo.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">En este caso, son habituales niveles muy elevados de preocupaci\u00f3n y agotamiento, junto a reacciones de frustraci\u00f3n permanente, ante todo lo que se percibe como insuficiente.<strong>\u00a0El perfeccionismo desadaptativo va mucho m\u00e1s all\u00e1 de la calidad.\u00a0<\/strong>Persigue lo impecable e insuperable, y todo aquello que no entra en estos est\u00e1ndares se considera fracaso.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Generalmente, los autoproclamados perfeccionistas terminan abandonando o postergando su proyecto por tiempo indefinido. La\u00a0<a class=\"jsx-151512268 jsx-1474443579 default-a-link is--underline c--secondary-600 is--underline\" href=\"https:\/\/reviberopsicologia.ibero.edu.co\/article\/view\/rip.5209\" target=\"_self\" rel=\"noopener\" data-with-google-events=\"true\" data-google-events=\"{&quot;data&quot;:{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;Content&quot;,&quot;label&quot;:&quot;Related \/utiliza-regla-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra\/?adsafe_ip=&quot;,&quot;value&quot;:&quot;https:\/\/reviberopsicologia.ibero.edu.co\/article\/view\/rip.5209&quot;}}\">procrastinaci\u00f3n<\/a>\u00a0est\u00e1 inherentemente vinculada a esta hiperexigencia por la perfecci\u00f3n.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Muchas personas, a la hora de sacar adelante una misi\u00f3n con alt\u00edsima expectativa, prefieren cancelar el proceso antes que tener que desafiarse a s\u00ed mismos para reevaluar las metas propuestas. Esto significa que\u00a0<strong>la obsesi\u00f3n por la excelencia puede ser contraproducente,\u00a0<\/strong>porque genera que las personas dejen de enfrentarse a tareas o disciplinas de su inter\u00e9s, por el simple hecho de eliminar la posibilidad de fallar.<\/p>\n<h3 id=\"perfeccionismo-adaptativo\" class=\"jsx-3692753319 jsx-2566528898 c--main-600  mt--x-big pt--normal\">Perfeccionismo adaptativo<\/h3>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">En su justa medida, ser perfeccionista puede servirle a las personas para motivarse a poner lo mejor de s\u00ed y as\u00ed mejorar en diferentes \u00e1reas de la vida. Este aspecto resulta adaptativo cuando est\u00e1 acompa\u00f1ado por otros rasgos de personalidad como la responsabilidad, organizaci\u00f3n, perseverancia.<b>\u00a0Es \u00fatil siempre y cuando se establezcan objetivos altos, pero realistas<\/b>.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">A su vez,\u00a0<strong>el perfeccionismo adaptativo suele convivir con una\u00a0<a class=\"jsx-151512268 jsx-1474443579 default-a-link is--underline c--secondary-600 is--underline\" href=\"https:\/\/lamenteesmaravillosa.com\/test-de-autoestima\/\" target=\"_self\" rel=\"noopener\" data-with-google-events=\"true\" data-google-events=\"{&quot;data&quot;:{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;Content&quot;,&quot;label&quot;:&quot;Related \/utiliza-regla-70-para-que-el-perfeccionismo-no-juegue-en-tu-contra\/&quot;,&quot;value&quot;:&quot;https:\/\/lamenteesmaravillosa.com\/test-de-autoestima\/&quot;}}\">autoestima<\/a>\u00a0saludable<\/strong>\u00a0porque la persona es capaz de identificar, valorar y potenciar sus fortalezas mientras que disfruta de sus conquistas. Su atenci\u00f3n no se focaliza exclusivamente en los resultados ni en lo que falta, sino que toma en cuenta el proceso de aprendizaje y aquello que logr\u00f3. En definitiva, se basa en la posibilidad de permitirse cometer errores y, a\u00fan as\u00ed, continuar intentando.<\/p>\n<h2 id=\"la-regla-del-70-ni-excelente-ni-mediocre\" class=\"jsx-3692753319 jsx-2566528898 c--main-600  mt--x-big pt--normal\">La regla del 70 %: ni excelente, ni mediocre<\/h2>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Afortunadamente, existen estrategias para dejar atr\u00e1s el perfeccionismo no saludable, sin que eso implique tener un desempe\u00f1o de baja calidad u obtener producciones mediocres.<strong>\u00a0\u00bfQu\u00e9 te parece esforzarte hasta conseguir un 70 % de perfecci\u00f3n?<\/strong>\u00a0Tan solo un poco menos excelente.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Te dar\u00e1s cuenta de que plantearte una meta posible de alcanzar, te dar\u00e1 la flexibilidad que necesitas para continuar creando, estudiando y trabajando. Seguir\u00e1s aprendiendo a trav\u00e9s de la pr\u00e1ctica, porque ya no est\u00e1 la imposici\u00f3n por hacer las cosas a la perfecci\u00f3n.<\/p>\n<div class=\"article-quote bc--secondary-50 ptb--big p--relative mb--normal mt--x-big\">\n<blockquote class=\"jsx-2118601352 jsx-2746653886 plr--big pt--big\">\n<div class=\"jsx-2118601352 jsx-2746653886 quote__text ta--center fs--italic lh--2 fs--normal ff--serif ls--medium c--secondary-800\">\n<p class=\"jsx-4098198752 c--grey-neutral-800\">\u201cMejor hacer algo imperfecto que no hacer nada sin falta alguna\u201d.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">-Robert Schuller-<\/p>\n<\/div>\n<\/blockquote>\n<h3 id=\"como-aplicarla\" class=\"jsx-3692753319 jsx-2566528898 c--main-600  mt--x-big pt--normal\">\u00bfC\u00f3mo aplicarla?<\/h3>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Si tiendes a esperar resultados 100 % \u00f3ptimos en tus trabajos, este m\u00e9todo te va a ayudar a entrar en acci\u00f3n y avanzar en todos tus pendientes esquivando la sobreexigencia, que es lo mismo que cuidar los recursos m\u00e1s valiosos con los que cuentas: tu tiempo y energ\u00eda.<\/p>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Veamos c\u00f3mo implementarla\u2026<\/p>\n<ul class=\"jsx-43291209 list-on-content mlr--x-big mtb--big c--grey-neutral-800 lh--1-8 ff--serif lst--disc\">\n<li>Cuando termines una tarea preg\u00fantate:\u00a0<strong>\u00bfesto est\u00e1 \u201cperfecto\u201d al 70 %?<\/strong><\/li>\n<li><strong>Si la respuesta es s\u00ed, puedes dar por terminada la tarea.<\/strong>\u00a0No tienes que esperar estar absolutamente seguro o conforme para entregar tu trabajo o publicar tu producci\u00f3n art\u00edstica. As\u00ed perder\u00edas muchas oportunidades, cr\u00edticas constructivas y aprendizajes, \u00bfcierto? Basta con estar satisfecho en un 70 % para lanzar a la luz tu creaci\u00f3n.<\/li>\n<li><strong>Si la respuesta es no, revisa lo siguiente: \u00bfqu\u00e9 necesito hacer o corregir para llegar a ese nivel?\u00a0<\/strong>Enf\u00f3cate en aquellas cuestiones que van a generar una mejora concreta, e intenta no dispersarte en el resto.<\/li>\n<\/ul>\n<p class=\"jsx-4098198752 c--grey-neutral-800\">Esta regla es una estrategia a largo plazo porque\u00a0<strong>te posibilita aumentar tu habilidad progresivamente<\/strong>, sin tener que ser perfecto cada d\u00eda. Si dejas de presionarte en componer una obra de arte magn\u00edfica en cada cosa que hagas, ver\u00e1s cu\u00e1ntas obras maestras aparecer\u00e1n en el camino.<\/p>\n<\/div>\n<p><a class=\"jsx-151512268 jsx-1596958326 default-a-link is--underline c--grey-neutral-800  link-tool-tip jsx-2288154920 jsx-986712099\" href=\"https:\/\/lamenteesmaravillosa.com\/autor\/sharon-laura-capeluto\/\" target=\"_self\" rel=\"noopener\"><strong>Sharon Laura Capeluto<\/strong><\/a>.<\/p>\n<div id=\"telet-3695861558\" class=\"telet-despues-del-contenido telet-entity-placement\"><a target=\"_blank\" href=\"\/\/aff.lucushost.com\/resources\/click\/?n=gDxoXMAJ&aff=756\"><img decoding=\"async\" border=\"0\" alt=\"LucusHost, el mejor hosting\" src=\"\/\/aff.lucushost.com\/resources\/banners\/?zoneid=5123&n=gDxoXMAJ&aff=756\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tengamos cuidado al plantearnos objetivos demasiado exigentes y esperar resultados \u00f3ptimos: puede ser contraproducente. Esta regla te ayudar\u00e1 a usar el perfeccionismo a tu favor. \u00a1Descubre c\u00f3mo! \u00bfSab\u00edas que el&hellip; <\/p>\n","protected":false},"author":1,"featured_media":9451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4],"tags":[20,19],"class_list":["post-9450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coaching","tag-fuprisa","tag-jose-manuel-fuentes-prieto"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"jetpack_featured_media_url":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-content\/uploads\/sites\/3\/2022\/06\/companeros-trabajando-hablando.jpg","_links":{"self":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/9450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/comments?post=9450"}],"version-history":[{"count":1,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/9450\/revisions"}],"predecessor-version":[{"id":9452,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/posts\/9450\/revisions\/9452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/media\/9451"}],"wp:attachment":[{"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/media?parent=9450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/categories?post=9450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teletrabajoynegocios.com\/teletrabajador\/wp-json\/wp\/v2\/tags?post=9450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}